{"id":6107,"date":"2025-08-29T09:08:58","date_gmt":"2025-08-29T07:08:58","guid":{"rendered":"https:\/\/vindhem.com\/event\/teddyz-rock-shrimp-taco-kreuzfahrt\/"},"modified":"2025-08-29T09:08:58","modified_gmt":"2025-08-29T07:08:58","slug":"teddyz-rock-shrimp-taco-kreuzfahrt","status":"publish","type":"mec-events","link":"https:\/\/vindhem.com\/de\/event\/teddyz-rock-shrimp-taco-kreuzfahrt\/","title":{"rendered":"Teddyz &#8211; Rock, Shrimp &amp; Taco Kreuzfahrt"},"content":{"rendered":"<p data-olk-copy-source=\"MessageBody\"><a href=\"https:\/\/www.instagram.com\/teddyz_sweden\"><strong>Teddyz<\/strong><\/a> &#8211; Eine musikalische Reise, bei der Sie singen und tanzen k\u00f6nnen, bis Sie nicht mehr aufstehen k\u00f6nnen, sind die Schl\u00fcsselw\u00f6rter!<\/p>\n<p>Teddyz ist die Band, die die Messlatte hoch ansetzt, wenn es um Unterhaltung geht. Wir spielen alle gro\u00dfen Hits, die Sie sich vorstellen k\u00f6nnen, alles von Schlager, Hardrock, Pop und Disco und passen uns immer an, um jeden in unserem Publikum zu erreichen. <\/p>\n<p>Unsere Energie ist ansteckend, und wir geben immer alles, um einen unvergesslichen Abend zu gestalten.<\/p>\n<p>Mit einer einzigartigen Lichtshow auf der B\u00fchne, kombiniert mit unserer F\u00e4higkeit, das Publikum mit einzubeziehen, hinterlassen wir immer einen Eindruck, der von allen gesch\u00e4tzt wird. Ob beim Apr\u00e8s-Ski in den Bergen oder nach dem Strand am Meer, wir sind viel auf Tournee und bieten sowohl gro\u00dfe als auch intime Auftritte. <\/p>\n<p>Erleben Sie einen Abend mit <a href=\"https:\/\/www.facebook.com\/profile.php?id=61579623794823&amp;mibextid=wwXIfr&amp;rdid=TceSBOtCF7M00boM&amp;share_url=https%3A%2F%2Fwww.facebook.com%2Fshare%2F1Z74MSrcGk%2F%3Fmibextid%3DwwXIfr#\">Teddyz<\/a> &#8211; wo die Musik verbindet, die Stimmung ansteigt und jeder mitmachen kann!<\/p>\n<p><strong>Unser Beitrag zu einem gelungenen Abend<\/strong> besteht aus unbegrenzt vielen Garnelen, frisch gebackenem Brot, Butter &amp; Aioli an Bord unseres Garnelenbootes.<br \/>\nAlternativ dazu gibt es Tacos mit Hackfleisch und allen traditionellen Beilagen. Der Taco kann vegetarisch und vegan zubereitet werden.<\/p>\n<p>Zum Nachtisch servieren wir ein K\u00e4setablett mit drei K\u00e4sesorten, Crackern und Weintrauben (nicht unbegrenzt).<\/p>\n<p>Ziehen Sie Ihre Tanzschuhe an und machen Sie sich bereit f\u00fcr einen Abend mit gutem Essen, viel Essen, toller Musik und Tanz auf dem sch\u00f6nsten Archipel der Welt.<\/p>\n<p><strong>Willkommen an Bord!<\/strong><\/p>\n<p><iframe title=\"TEDDYZ LIVE p\u00e5 Solga\u030arden Tylo\u0308sand\" width=\"563\" height=\"1000\" src=\"https:\/\/www.youtube.com\/embed\/gI3Fl78lVcE?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Unterer Salon<\/strong> SEK 639<br \/><strong>Oberer Salon<\/strong> SEK 639<br \/><strong>Kinder 7-12 Jahre<\/strong> SEK 320<br \/><strong>Kinder 0-6 Jahre<\/strong> Kostenlos<\/p>\n","protected":false},"author":7,"featured_media":6103,"comment_status":"closed","ping_status":"closed","template":"","tags":[],"mec_category":[68],"class_list":["post-6107","mec-events","type-mec-events","status-publish","has-post-thumbnail","hentry","mec_category-shrimp-rock-abend"],"acf":[],"_links":{"self":[{"href":"https:\/\/vindhem.com\/de\/wp-json\/wp\/v2\/mec-events\/6107","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vindhem.com\/de\/wp-json\/wp\/v2\/mec-events"}],"about":[{"href":"https:\/\/vindhem.com\/de\/wp-json\/wp\/v2\/types\/mec-events"}],"author":[{"embeddable":true,"href":"https:\/\/vindhem.com\/de\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/vindhem.com\/de\/wp-json\/wp\/v2\/comments?post=6107"}],"version-history":[{"count":0,"href":"https:\/\/vindhem.com\/de\/wp-json\/wp\/v2\/mec-events\/6107\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vindhem.com\/de\/wp-json\/wp\/v2\/media\/6103"}],"wp:attachment":[{"href":"https:\/\/vindhem.com\/de\/wp-json\/wp\/v2\/media?parent=6107"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vindhem.com\/de\/wp-json\/wp\/v2\/tags?post=6107"},{"taxonomy":"mec_category","embeddable":true,"href":"https:\/\/vindhem.com\/de\/wp-json\/wp\/v2\/mec_category?post=6107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}